{"id":1,"date":"2011-11-24T23:00:47","date_gmt":"2011-11-24T23:00:47","guid":{"rendered":"http:\/\/www.contrapunktonline.de\/content\/?p=1"},"modified":"2012-03-13T14:04:37","modified_gmt":"2012-03-13T13:04:37","slug":"36-indien-unendliche-moeglichkeiten","status":"publish","type":"post","link":"https:\/\/www.contrapunktonline.de\/content\/36-indien-unendliche-moeglichkeiten\/","title":{"rendered":"36 \u2013 Indien \u2013 Unendliche M\u00f6glichkeiten"},"content":{"rendered":"<div id=\"attachment_8\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/indien.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-8\" class=\"size-medium wp-image-8\" title=\"Flagge Indien\" src=\"http:\/\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/indien-300x199.png\" alt=\"Flagge Indien\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/indien-300x199.png 300w, https:\/\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/indien.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-8\" class=\"wp-caption-text\">Flagge Indien<\/p><\/div>\n<p><strong>24.11.2011 \u2013 Goethe-Forum M\u00fcnchen<\/strong><br \/>\nDialog der Kulturen:\u00a0Ausgabe Nr. 36<br \/>\nModeration: \u00a0Eva Schrot, \u00a0Theo Gei\u00dfler<br \/>\nRedaktion: Meret Forster<\/p>\n<p>Im vergangenen August \u00e4hnelten Bilder aus Indien denen vom \u201earabischen Fr\u00fchling\u201c: Gro\u00dfdemonstrationen gegen die Regierung in den Stra\u00dfen der Metropolen. Man sprach bereits von Indiens zweitem Unabh\u00e4ngigkeitskampf \u2013 ausgel\u00f6st vom Hungerstreik eines Anti-Korruptions-Aktivisten. Eine neue indische Mittelklasse, die sich in den letzten 20 Jahren entwickelt hat, f\u00fcrchtet um ihren Status. Zorn \u00fcber die Korruption treibt sie an. Ihnen ist bewusst, dass diese ein Land in vielen Bereichen wirtschaftlich und politisch zur\u00fcckwerfen kann. Seit Beginn der 90er Jahre entwickelte sich die gr\u00f6\u00dfte Demokratie der Welt zur drittgr\u00f6\u00dften Wirtschaftsmacht Asiens.\u00a0<!--more--><\/p>\n<p>Aus Anlass des 60-j\u00e4hrigen Bestehens der diplomatischen Beziehungen zwischen Deutschland und Indien findet noch bis Ende 2012 das Deutschlandjahr in Indien statt, das in sieben Metropolen Veranstaltungen aus Kultur, Bildung, Forschung, Wirtschaft und Politik pr\u00e4sentieren wird.<\/p>\n<p>++ contrapunkt++ interessiert sich hier speziell f\u00fcr die Musikprojekte des Deutschlandjahres, wirft aber auch einen Blick auf die Musiktraditionen Indiens.++ Auch der bekannte Dichter Rabindrantath Tagore steht im Fokus, der erste au\u00dferhalb des westlichen Kulturkreises, der 1913 den Literaturnobelpreis erhielt und dessen 150. Geburtstag in diesem Jahr gefeiert wird.<\/p>\n<p><strong>G\u00e4ste:<\/strong><\/p>\n<ul>\n<li>Bernd Franke, Komponist<\/li>\n<li>Debarati Guha, Journalistin<\/li>\n<li>Hans Harder, Indologe<\/li>\n<\/ul>\n<p><strong>Live-Musik:<\/strong><\/p>\n<ul>\n<li>Subroto Roy Chowdhury \u2013 Sitar<\/li>\n<li>Arup Sengupta \u2013 Tabla<\/li>\n<li>Herbert Lang &#8211; Mridangam \/ Kanjira<\/li>\n<li>Saikat Bhattacharya &#8211; Gesang<\/li>\n<\/ul>\n<p>Ein Themenabend im Goethe-Forum mit Film (19.00 Uhr), Musik, Kulinarik &amp; Diskussion \u2013 und live auf BR-Klassik (21.03 \u2013 22.00 Uhr). In Zusammenarbeit mit dem Goethe-Institut\/Max Mueller Bhavan New-Delhi und dem Indien-Institut, M\u00fcnchen.<\/p>\n<h4>Sendung nachh\u00f6ren:<\/h4>\n<div class=\"powerpress_player\" id=\"powerpress_player_2882\"><a href=\"http:\/\/media.blubrry.com\/contrapunkt\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/36-00.mp3\" title=\"Play\" onclick=\"return powerpress_embed_html5a('2882','http:\/\/media.blubrry.com\/contrapunkt\/www.contrapunktonline.de\/content\/wp-content\/uploads\/2012\/03\/36-00.mp3');\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.contrapunktonline.de\/content\/wp-content\/uploads\/powerpress\/play.gif\" title=\"Play\" alt=\"Play\" style=\"border:0;\" \/><\/a><\/div>\n\n<p>3:36 (1) <strong>Einf\u00fchrung ins Thema<\/strong><br \/>\nBegr\u00fc\u00dfung: Theo Gei\u00dfler und Eva Schrot stellen das Thema vor.<\/p>\n<p>3:52 (2) <strong>Bericht \u201eIndien\u201c<\/strong><br \/>\nBR-Korrespondent Christoph Hahn \u00fcber die aktuelle Lage der Kultur in Indien.<\/p>\n<p>9:11 (3) <strong>Vorstellung der G\u00e4ste und Gespr\u00e4ch<\/strong><br \/>\nBegr\u00fc\u00dfung der G\u00e4ste: Debarati Guha, Hans Harder, Bernd Franke. Mit Gesangseinlage. Demokratie, Filmindustrie, Musik. Sinneserweiterung.<\/p>\n<p>3:12 (4) <strong>Live-Musik: Komme, o sch\u00f6ne Regenzeit (Tagore)<\/strong><br \/>\nSubroto Roy Chowdhury \u2013 Sitar, Arup Sengupta \u2013 Tabla, Herbert Lang &#8211; Mridangam \/ Kanjira Saikat Bhattacharya &#8211; Gesang<\/p>\n<p>22:35 (5) <strong>Diskussion I<\/strong><br \/>\nTagore \u2013 Rilke \u2013 Musikalische Wanderungen \u2013 Generationenkonflikt \u2013 Durchdringung von Ost und West \u2013 Tradition \u2013 Liebe zum Singen \u2013 Was geht ab? \u2013<\/p>\n<p>5:27 (6) <strong>Live-Musik: Raga im 7\/8-Takt<\/strong><br \/>\nSubroto Roy Chowdhury \u2013 Sitar, Arup Sengupta \u2013 Tabla, Herbert Lang &#8211; Mridangam \/ Kanjira Saikat Bhattacharya &#8211; Gesang<\/p>\n<p>6:40 (7) <strong>Diskussion II<\/strong><br \/>\nIndien &amp; Politik \u2013 Lehrer&amp;Sch\u00fcler \u2013 Noten<\/p>\n<p>2:11 (8) <strong>Live-Musik: Tagore-Lied<\/strong><br \/>\nSubroto Roy Chowdhury \u2013 Sitar, Arup Sengupta \u2013 Tabla, Herbert Lang &#8211; Mridangam \/ Kanjira Saikat Bhattacharya &#8211; Gesang<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\"><div class=\"ShariffHeadline\"> <\/div><ul class=\"shariff-buttons theme-default orientation-horizontal buttonsize-medium\"><li class=\"shariff-button bluesky shariff-nocustomcolor\" style=\"background-color:#84c4ff\"><a href=\"https:\/\/bsky.app\/intent\/compose?text=36%20%E2%80%93%20Indien%20%E2%80%93%20Unendliche%20M%C3%B6glichkeiten https%3A%2F%2Fwww.contrapunktonline.de%2Fcontent%2F36-indien-unendliche-moeglichkeiten%2F \" title=\"Bei Bluesky teilen\" aria-label=\"Bei Bluesky teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0085ff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"20\" height=\"20\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 20 20\"><path class=\"st0\" d=\"M4.89,3.12c2.07,1.55,4.3,4.71,5.11,6.4.82-1.69,3.04-4.84,5.11-6.4,1.49-1.12,3.91-1.99,3.91.77,0,.55-.32,4.63-.5,5.3-.64,2.3-2.99,2.89-5.08,2.54,3.65.62,4.58,2.68,2.57,4.74-3.81,3.91-5.48-.98-5.9-2.23-.08-.23-.11-.34-.12-.25,0-.09-.04.02-.12.25-.43,1.25-2.09,6.14-5.9,2.23-2.01-2.06-1.08-4.12,2.57-4.74-2.09.36-4.44-.23-5.08-2.54-.19-.66-.5-4.74-.5-5.3,0-2.76,2.42-1.89,3.91-.77h0Z\"\/><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button mastodon shariff-nocustomcolor\" style=\"background-color:#563ACC\"><a href=\"https:\/\/s2f.kytta.dev\/?text=36%20%E2%80%93%20Indien%20%E2%80%93%20Unendliche%20M%C3%B6glichkeiten https%3A%2F%2Fwww.contrapunktonline.de%2Fcontent%2F36-indien-unendliche-moeglichkeiten%2F\" title=\"Bei Mastodon teilen\" aria-label=\"Bei Mastodon teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#6364FF; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"75\" height=\"79\" viewBox=\"0 0 75 79\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M37.813-.025C32.462-.058 27.114.13 21.79.598c-8.544.621-17.214 5.58-20.203 13.931C-1.12 23.318.408 32.622.465 41.65c.375 7.316.943 14.78 3.392 21.73 4.365 9.465 14.781 14.537 24.782 15.385 7.64.698 15.761-.213 22.517-4.026a54.1 54.1 0 0 0 .01-6.232c-6.855 1.316-14.101 2.609-21.049 1.074-3.883-.88-6.876-4.237-7.25-8.215-1.53-3.988 3.78-.43 5.584-.883 9.048 1.224 18.282.776 27.303-.462 7.044-.837 14.26-4.788 16.65-11.833 2.263-6.135 1.215-12.79 1.698-19.177.06-3.84.09-7.692-.262-11.52C72.596 7.844 63.223.981 53.834.684a219.453 219.453 0 0 0-16.022-.71zm11.294 12.882c5.5-.067 10.801 4.143 11.67 9.653.338 1.48.471 3 .471 4.515v21.088h-8.357c-.07-7.588.153-15.182-.131-22.765-.587-4.368-7.04-5.747-9.672-2.397-2.422 3.04-1.47 7.155-1.67 10.735v6.392h-8.307c-.146-4.996.359-10.045-.404-15.002-1.108-4.218-7.809-5.565-10.094-1.666-1.685 3.046-.712 6.634-.976 9.936v14.767h-8.354c.109-8.165-.238-16.344.215-24.5.674-5.346 5.095-10.389 10.676-10.627 4.902-.739 10.103 2.038 12.053 6.631.375 1.435 1.76 1.932 1.994.084 1.844-3.704 5.501-6.739 9.785-6.771.367-.044.735-.068 1.101-.073z\"\/><defs><linearGradient id=\"paint0_linear_549_34\" x1=\"37.0692\" y1=\"0\" x2=\"37.0692\" y2=\"79\" gradientUnits=\"userSpaceOnUse\"><stop stop-color=\"#6364FF\"\/><stop offset=\"1\" stop-color=\"#563ACC\"\/><\/linearGradient><\/defs><\/svg><\/span><span class=\"shariff-text\">teilen<\/span>&nbsp;<\/a><\/li><li class=\"shariff-button info shariff-nocustomcolor\" style=\"background-color:#eee\"><a href=\"http:\/\/ct.de\/-2467514\" title=\"Weitere Informationen\" aria-label=\"Weitere Informationen\" role=\"button\" rel=\"noopener \" class=\"shariff-link\" style=\"; background-color:#fff; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 11 32\"><path fill=\"#999\" d=\"M11.4 24v2.3q0 0.5-0.3 0.8t-0.8 0.4h-9.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h1.1v-6.8h-1.1q-0.5 0-0.8-0.4t-0.4-0.8v-2.3q0-0.5 0.4-0.8t0.8-0.4h6.8q0.5 0 0.8 0.4t0.4 0.8v10.3h1.1q0.5 0 0.8 0.4t0.3 0.8zM9.2 3.4v3.4q0 0.5-0.4 0.8t-0.8 0.4h-4.6q-0.4 0-0.8-0.4t-0.4-0.8v-3.4q0-0.4 0.4-0.8t0.8-0.4h4.6q0.5 0 0.8 0.4t0.4 0.8z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Aus Anlass des 60-j\u00e4hrigen Bestehens der diplomatischen Beziehungen zwischen Deutschland und Indien findet noch bis Ende 2012 das Deutschlandjahr in Indien statt, das in sieben Metropolen Veranstaltungen aus Kultur, Bildung, Forschung, Wirtschaft und Politik pr\u00e4sentieren wird. ++ contrapunkt ++ interessiert sich hier speziell f\u00fcr die Musikprojekte des Deutschlandjahres, wirft aber auch einen Blick auf die Musiktraditionen Indiens. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[16,5,10],"tags":[3,4,48],"class_list":["post-1","post","type-post","status-publish","format-standard","hentry","category-br-klassik","category-dialog-der-kulturen","category-goethe-institut","tag-asien","tag-indien","tag-orient"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/posts\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":17,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":5,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/posts\/1\/revisions\/5"}],"wp:attachment":[{"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.contrapunktonline.de\/content\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}